{"id":10589,"date":"2023-09-20T12:07:01","date_gmt":"2023-09-20T17:07:01","guid":{"rendered":"https:\/\/naturapanama.org\/?p=10589"},"modified":"2023-11-07T13:54:02","modified_gmt":"2023-11-07T18:54:02","slug":"parque-nacional-isla-bastimentos-poa-2021","status":"publish","type":"post","link":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/","title":{"rendered":"Parque Nacional Isla Bastimentos (POA 2021)"},"content":{"rendered":"\n<p><strong>Financiado por:<\/strong>&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO.<\/p>\n\n\n\n<p><strong>Entidad Ejecutora:<\/strong>&nbsp;MiAmbiente<\/p>\n\n\n\n<p><strong>Monto Total:<\/strong>&nbsp;B\/. 164,340.00<br><strong>Aporte de FIDECO:<\/strong> B\/. 114,800.00<br><strong>Aporte de Contrapartida:<\/strong> B\/. 49,540.00<\/p>\n\n\n\n<p><strong>Fecha: <\/strong>En ejecuci\u00f3n<\/p>\n\n\n\n<p><strong>\u00c1rea Program\u00e1tica:&nbsp;<\/strong> Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas.<\/p>\n\n\n\n<p><strong>Actividades:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elaborar artes e impresi\u00f3n de material divulgativo<\/li>\n\n\n\n<li>Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos<\/li>\n\n\n\n<li>Se adjudic\u00f3 el Contrato a la empresa S&amp;L Services S.A. para:<\/li>\n\n\n\n<li>Ampliaci\u00f3n de las rampas de acceso del muelle de 16 pies m\u00e1s de largo para facilitar el embarque y desembarque de los visitantes en Cayo Zapatilla #2 y pasamanos en la escalera de la casa y Adecuaci\u00f3n, adquisici\u00f3n e instalaci\u00f3n de tres tanques, para el almacenamiento de agua para la casa de guardaparques<\/li>\n\n\n\n<li>Habilitaci\u00f3n de 165 metros de sendero de terrestre y 100 metros de sendero elevado de madera pl\u00e1stica<\/li>\n\n\n\n<li>&nbsp;Ampliaci\u00f3n del sistema de energ\u00eda con paneles solares del refugio en Cayo Zapatilla<\/li>\n\n\n\n<li>Adquisici\u00f3n de equipos e insumos de bioseguridad COVID-19, tales como: Alcohol 70%, Jab\u00f3n L\u00edquido de Mano, Mascarillas Quir\u00fargicas, Clorox, Protectores faciales, Gel alcoholado 70%, Dispensador tipo Pedestal (4), term\u00f3metro digital infrarrojo (3), Guantes de l\u00e1tex, Pediluvio de desinfecci\u00f3n (3), Amonio Cuaternario.<\/li>\n\n\n\n<li>Adquisici\u00f3n de repuestos de acuerdo a la necesidad (motores fuera de borda, motosierras, lanchas)<\/li>\n\n\n\n<li>Adquisici\u00f3n de 4 equipos de buceo, (trajes de neopreno, Reguladores, Chalecos, Aletas, cinturones con lastre, m\u00e1scaras y snorkel)<\/li>\n\n\n\n<li>Confecci\u00f3n e instalaci\u00f3n de 2 letreros grande (mapa) del circuito completo del sendero las bromelias, y 10 letreros para se\u00f1alizar infraestructuras centro de informaci\u00f3n, rancho merendero, Ba\u00f1os, duchas, cambiadores, casa de guardaparques, senderos. Ubicados en Cayo Zapatilla #2<\/li>\n\n\n\n<li>Se realiz\u00f3 la sesi\u00f3n de PMEMAP del \u00e1rea protegida en el mes de junio 2022.<\/li>\n\n\n\n<li>Pendiente realizar la divulgaci\u00f3n de los resultados PMEMAP 2022 con las comunidades<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Financiado por:&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO. Entidad Ejecutora:&nbsp;MiAmbiente Monto Total:&nbsp;B\/. 164,340.00Aporte de FIDECO: B\/. 114,800.00Aporte de Contrapartida: B\/. 49,540.00 Fecha: En ejecuci\u00f3n \u00c1rea Program\u00e1tica:&nbsp; Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas. Actividades: Elaborar artes e impresi\u00f3n de material divulgativo Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos Se adjudic\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[42],"tags":[62,73],"class_list":["post-10589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects","tag-fideco","tag-programa-de-donaciones-a-las-areas-protegidas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parque Nacional Isla Bastimentos (POA 2021)<\/title>\n<meta name=\"description\" content=\"Financiado por:&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO. Entidad Ejecutora:&nbsp;MiAmbiente Monto Total:&nbsp;B\/. 164,340.00Aporte de FIDECO: B\/. 114,800.00Aporte de Contrapartida: B\/. 49,540.00 Fecha: En ejecuci\u00f3n \u00c1rea Program\u00e1tica:&nbsp; Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas. Actividades: Elaborar artes e impresi\u00f3n de material divulgativo Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos Se adjudic\u00f3&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parque Nacional Isla Bastimentos (POA 2021)\" \/>\n<meta property=\"og:description\" content=\"Financiado por:&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO. Entidad Ejecutora:&nbsp;MiAmbiente Monto Total:&nbsp;B\/. 164,340.00Aporte de FIDECO: B\/. 114,800.00Aporte de Contrapartida: B\/. 49,540.00 Fecha: En ejecuci\u00f3n \u00c1rea Program\u00e1tica:&nbsp; Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas. Actividades: Elaborar artes e impresi\u00f3n de material divulgativo Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos Se adjudic\u00f3&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci&oacute;n Natura\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naturapma\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T17:07:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T18:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturapanama.org\/wp-content\/uploads\/2023\/11\/PNMIB-4-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naturapanama\" \/>\n<meta name=\"twitter:site\" content=\"@naturapanama\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#\\\/schema\\\/person\\\/bb437b41a01c2ea2d8c1bb2016373329\"},\"headline\":\"Parque Nacional Isla Bastimentos (POA 2021)\",\"datePublished\":\"2023-09-20T17:07:01+00:00\",\"dateModified\":\"2023-11-07T18:54:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/PNMIB-4-1.jpg\",\"keywords\":[\"FIDECO\",\"Programa de Donaciones a las \u00c1reas Protegidas\"],\"articleSection\":[\"Projects\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/\",\"name\":\"Parque Nacional Isla Bastimentos (POA 2021) &#060; Fundaci&oacute;n Natura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/PNMIB-4-1.jpg\",\"datePublished\":\"2023-09-20T17:07:01+00:00\",\"dateModified\":\"2023-11-07T18:54:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/PNMIB-4-1.jpg\",\"contentUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/PNMIB-4-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/parque-nacional-isla-bastimentos-poa-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/naturapanama.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parque Nacional Isla Bastimentos (POA 2021)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/\",\"name\":\"Fundaci\u00f3n Natura\",\"description\":\"Fundaci&oacute;n Natura es reconocida como gestor de recursos, que lidera e innova en la conservaci&oacute;n y el manejo sostenible de ecosistemas y su biodiversidad en las cuencas hidrogr&aacute;ficas y &aacute;reas marino costeras priorizadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#organization\",\"name\":\"Fundacion Natura\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-Recurso-3@4x.png\",\"contentUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-Recurso-3@4x.png\",\"width\":512,\"height\":512,\"caption\":\"Fundacion Natura\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/naturapma\\\/\",\"https:\\\/\\\/x.com\\\/naturapanama\",\"https:\\\/\\\/www.instagram.com\\\/naturapma\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWu_h9ovqfg_vR2RlGe9UfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#\\\/schema\\\/person\\\/bb437b41a01c2ea2d8c1bb2016373329\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/naturapanama.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parque Nacional Isla Bastimentos (POA 2021)","description":"Financiado por:&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO. Entidad Ejecutora:&nbsp;MiAmbiente Monto Total:&nbsp;B\/. 164,340.00Aporte de FIDECO: B\/. 114,800.00Aporte de Contrapartida: B\/. 49,540.00 Fecha: En ejecuci\u00f3n \u00c1rea Program\u00e1tica:&nbsp; Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas. Actividades: Elaborar artes e impresi\u00f3n de material divulgativo Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos Se adjudic\u00f3&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Financiado por:&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO. Entidad Ejecutora:&nbsp;MiAmbiente Monto Total:&nbsp;B\/. 164,340.00Aporte de FIDECO: B\/. 114,800.00Aporte de Contrapartida: B\/. 49,540.00 Fecha: En ejecuci\u00f3n \u00c1rea Program\u00e1tica:&nbsp; Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas. Actividades: Elaborar artes e impresi\u00f3n de material divulgativo Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos Se adjudic\u00f3&hellip;","og_locale":"en_US","og_type":"article","og_title":"Parque Nacional Isla Bastimentos (POA 2021)","og_description":"Financiado por:&nbsp;Fideicomiso ecol\u00f3gico de Panam\u00e1, Fondo FIDECO. Entidad Ejecutora:&nbsp;MiAmbiente Monto Total:&nbsp;B\/. 164,340.00Aporte de FIDECO: B\/. 114,800.00Aporte de Contrapartida: B\/. 49,540.00 Fecha: En ejecuci\u00f3n \u00c1rea Program\u00e1tica:&nbsp; Fortalecimiento del Sistema Nacional de \u00c1reas Protegidas. Actividades: Elaborar artes e impresi\u00f3n de material divulgativo Se elabor\u00f3 los materiales divulgativos del \u00e1rea protegida los cuales han sido distribuidos Se adjudic\u00f3&hellip;","og_url":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/","og_site_name":"Fundaci&oacute;n Natura","article_publisher":"https:\/\/www.facebook.com\/naturapma\/","article_published_time":"2023-09-20T17:07:01+00:00","article_modified_time":"2023-11-07T18:54:02+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2023\/11\/PNMIB-4-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@naturapanama","twitter_site":"@naturapanama","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#article","isPartOf":{"@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/"},"author":{"name":"admin","@id":"https:\/\/naturapanama.org\/#\/schema\/person\/bb437b41a01c2ea2d8c1bb2016373329"},"headline":"Parque Nacional Isla Bastimentos (POA 2021)","datePublished":"2023-09-20T17:07:01+00:00","dateModified":"2023-11-07T18:54:02+00:00","mainEntityOfPage":{"@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/"},"wordCount":315,"publisher":{"@id":"https:\/\/naturapanama.org\/#organization"},"image":{"@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2023\/11\/PNMIB-4-1.jpg","keywords":["FIDECO","Programa de Donaciones a las \u00c1reas Protegidas"],"articleSection":["Projects"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/","url":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/","name":"Parque Nacional Isla Bastimentos (POA 2021) &#060; Fundaci&oacute;n Natura","isPartOf":{"@id":"https:\/\/naturapanama.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#primaryimage"},"image":{"@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2023\/11\/PNMIB-4-1.jpg","datePublished":"2023-09-20T17:07:01+00:00","dateModified":"2023-11-07T18:54:02+00:00","breadcrumb":{"@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#primaryimage","url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2023\/11\/PNMIB-4-1.jpg","contentUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2023\/11\/PNMIB-4-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/naturapanama.org\/en\/parque-nacional-isla-bastimentos-poa-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/naturapanama.org\/"},{"@type":"ListItem","position":2,"name":"Parque Nacional Isla Bastimentos (POA 2021)"}]},{"@type":"WebSite","@id":"https:\/\/naturapanama.org\/en\/#website","url":"https:\/\/naturapanama.org\/en\/","name":"Fundaci\u00f3n Natura","description":"Fundaci&oacute;n Natura es reconocida como gestor de recursos, que lidera e innova en la conservaci&oacute;n y el manejo sostenible de ecosistemas y su biodiversidad en las cuencas hidrogr&aacute;ficas y &aacute;reas marino costeras priorizadas","publisher":{"@id":"https:\/\/naturapanama.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturapanama.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/naturapanama.org\/en\/#organization","name":"Fundacion Natura","url":"https:\/\/naturapanama.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturapanama.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2021\/08\/cropped-Recurso-3@4x.png","contentUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2021\/08\/cropped-Recurso-3@4x.png","width":512,"height":512,"caption":"Fundacion Natura"},"image":{"@id":"https:\/\/naturapanama.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naturapma\/","https:\/\/x.com\/naturapanama","https:\/\/www.instagram.com\/naturapma\/","https:\/\/www.youtube.com\/channel\/UCWu_h9ovqfg_vR2RlGe9UfA"]},{"@type":"Person","@id":"https:\/\/naturapanama.org\/#\/schema\/person\/bb437b41a01c2ea2d8c1bb2016373329","name":"admin","sameAs":["https:\/\/naturapanama.org"]}]}},"_links":{"self":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/10589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/comments?post=10589"}],"version-history":[{"count":2,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/10589\/revisions"}],"predecessor-version":[{"id":10708,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/10589\/revisions\/10708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/media\/10709"}],"wp:attachment":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/media?parent=10589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/categories?post=10589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/tags?post=10589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}