{"id":11501,"date":"2025-03-02T21:14:08","date_gmt":"2025-03-03T02:14:08","guid":{"rendered":"https:\/\/naturapanama.org\/?p=11501"},"modified":"2025-05-15T12:43:46","modified_gmt":"2025-05-15T17:43:46","slug":"contratacion-de-coordinador-financiero-de-programa","status":"publish","type":"post","link":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/","title":{"rendered":"Contrataci\u00f3n de Coordinador Financiero de Programa"},"content":{"rendered":"\n<p>Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y en planificaci\u00f3n y control presupuestario por central de costos, a aplicar a la vacante Coordinador Financiero De Programa.<\/p>\n\n\n\n<p>Fecha l\u00edmite para aplicar: 14 de marzo de 2025 hasta las 3:00 p.m.<\/p>\n\n\n\n<p>Para aplicar enviar correo a jdiaz@naturapanama.org&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/ANUNCIO-DE-VACANTE_FN-07-2025_CFP.doc\">Conoce los requisitos en el siguiente anuncio de vacante.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-11501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vacantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contrataci\u00f3n de Coordinador Financiero de Programa<\/title>\n<meta name=\"description\" content=\"Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Se%20invita%20a%20Profesionales%20con%20nivel%20de%20Licenciatura%20en%20Banca%20y%20Finanzas,%20con%20m\u00ednimo%20de%203%20a\u00f1os%20de%20experiencia%20en%20trabajos%20relacionados%20a%20los%20temas%20solicitados%20en%20el%20puesto,%20con%20facilidad%20de%20expresi\u00f3n,%20redacci\u00f3n%20de%20documentos%20e%20informes%20y%20administraci\u00f3n%20de%20bienes%20y%20servicios%20y%20con%20experiencia%20en%20la%20Explotaci\u00f3n%20de%20Datos%20(Data%20Minning)%20y&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contrataci\u00f3n de Coordinador Financiero de Programa\" \/>\n<meta property=\"og:description\" content=\"Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci&oacute;n Natura\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naturapma\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-03T02:14:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T17:43:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2071\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Comunicaciones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naturapanama\" \/>\n<meta name=\"twitter:site\" content=\"@naturapanama\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/\"},\"author\":{\"name\":\"Comunicaciones\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#\\\/schema\\\/person\\\/9a635c59f5d7459c52e2d5ce79952b48\"},\"headline\":\"Contrataci\u00f3n de Coordinador Financiero de Programa\",\"datePublished\":\"2025-03-03T02:14:08+00:00\",\"dateModified\":\"2025-05-15T17:43:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/\"},\"wordCount\":116,\"publisher\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp\",\"articleSection\":[\"Vacancies\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/\",\"name\":\"Contrataci\u00f3n de Coordinador Financiero de Programa &#060; Fundaci&oacute;n Natura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp\",\"datePublished\":\"2025-03-03T02:14:08+00:00\",\"dateModified\":\"2025-05-15T17:43:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp\",\"width\":2071,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/contratacion-de-coordinador-financiero-de-programa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/naturapanama.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contrataci\u00f3n de Coordinador Financiero de Programa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/\",\"name\":\"Fundaci\u00f3n Natura\",\"description\":\"Fundaci&oacute;n Natura es reconocida como gestor de recursos, que lidera e innova en la conservaci&oacute;n y el manejo sostenible de ecosistemas y su biodiversidad en las cuencas hidrogr&aacute;ficas y &aacute;reas marino costeras priorizadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#organization\",\"name\":\"Fundacion Natura\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-Recurso-3@4x.png\",\"contentUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-Recurso-3@4x.png\",\"width\":512,\"height\":512,\"caption\":\"Fundacion Natura\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/naturapma\\\/\",\"https:\\\/\\\/x.com\\\/naturapanama\",\"https:\\\/\\\/www.instagram.com\\\/naturapma\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWu_h9ovqfg_vR2RlGe9UfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#\\\/schema\\\/person\\\/9a635c59f5d7459c52e2d5ce79952b48\",\"name\":\"Comunicaciones\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contrataci\u00f3n de Coordinador Financiero de Programa","description":"Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y&hellip;","og_locale":"en_US","og_type":"article","og_title":"Contrataci\u00f3n de Coordinador Financiero de Programa","og_description":"Se invita a Profesionales con nivel de Licenciatura en Banca y Finanzas, con m\u00ednimo de 3 a\u00f1os de experiencia en trabajos relacionados a los temas solicitados en el puesto, con facilidad de expresi\u00f3n, redacci\u00f3n de documentos e informes y administraci\u00f3n de bienes y servicios y con experiencia en la Explotaci\u00f3n de Datos (Data Minning) y&hellip;","og_url":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/","og_site_name":"Fundaci&oacute;n Natura","article_publisher":"https:\/\/www.facebook.com\/naturapma\/","article_published_time":"2025-03-03T02:14:08+00:00","article_modified_time":"2025-05-15T17:43:46+00:00","og_image":[{"width":2071,"height":2560,"url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp","type":"image\/webp"}],"author":"Comunicaciones","twitter_card":"summary_large_image","twitter_creator":"@naturapanama","twitter_site":"@naturapanama","twitter_misc":{"Written by":"Comunicaciones","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#article","isPartOf":{"@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/"},"author":{"name":"Comunicaciones","@id":"https:\/\/naturapanama.org\/#\/schema\/person\/9a635c59f5d7459c52e2d5ce79952b48"},"headline":"Contrataci\u00f3n de Coordinador Financiero de Programa","datePublished":"2025-03-03T02:14:08+00:00","dateModified":"2025-05-15T17:43:46+00:00","mainEntityOfPage":{"@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/"},"wordCount":116,"publisher":{"@id":"https:\/\/naturapanama.org\/#organization"},"image":{"@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#primaryimage"},"thumbnailUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp","articleSection":["Vacancies"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/","url":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/","name":"Contrataci\u00f3n de Coordinador Financiero de Programa &#060; Fundaci&oacute;n Natura","isPartOf":{"@id":"https:\/\/naturapanama.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#primaryimage"},"image":{"@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#primaryimage"},"thumbnailUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp","datePublished":"2025-03-03T02:14:08+00:00","dateModified":"2025-05-15T17:43:46+00:00","breadcrumb":{"@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#primaryimage","url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp","contentUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/03\/Convocatoria_-Licenciatura-en-Banca-y-Finanzas-scaled.webp","width":2071,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/naturapanama.org\/en\/contratacion-de-coordinador-financiero-de-programa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/naturapanama.org\/"},{"@type":"ListItem","position":2,"name":"Contrataci\u00f3n de Coordinador Financiero de Programa"}]},{"@type":"WebSite","@id":"https:\/\/naturapanama.org\/en\/#website","url":"https:\/\/naturapanama.org\/en\/","name":"Fundaci\u00f3n Natura","description":"Fundaci&oacute;n Natura es reconocida como gestor de recursos, que lidera e innova en la conservaci&oacute;n y el manejo sostenible de ecosistemas y su biodiversidad en las cuencas hidrogr&aacute;ficas y &aacute;reas marino costeras priorizadas","publisher":{"@id":"https:\/\/naturapanama.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturapanama.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/naturapanama.org\/en\/#organization","name":"Fundacion Natura","url":"https:\/\/naturapanama.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturapanama.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2021\/08\/cropped-Recurso-3@4x.png","contentUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2021\/08\/cropped-Recurso-3@4x.png","width":512,"height":512,"caption":"Fundacion Natura"},"image":{"@id":"https:\/\/naturapanama.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naturapma\/","https:\/\/x.com\/naturapanama","https:\/\/www.instagram.com\/naturapma\/","https:\/\/www.youtube.com\/channel\/UCWu_h9ovqfg_vR2RlGe9UfA"]},{"@type":"Person","@id":"https:\/\/naturapanama.org\/#\/schema\/person\/9a635c59f5d7459c52e2d5ce79952b48","name":"Comunicaciones"}]}},"_links":{"self":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/11501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/comments?post=11501"}],"version-history":[{"count":4,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/11501\/revisions"}],"predecessor-version":[{"id":11562,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/11501\/revisions\/11562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/media\/11500"}],"wp:attachment":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/media?parent=11501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/categories?post=11501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/tags?post=11501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}