{"id":12669,"date":"2025-06-30T16:15:20","date_gmt":"2025-06-30T21:15:20","guid":{"rendered":"https:\/\/naturapanama.org\/?p=12669"},"modified":"2025-07-28T16:21:50","modified_gmt":"2025-07-28T21:21:50","slug":"fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos","status":"publish","type":"post","link":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/","title":{"rendered":"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos"},"content":{"rendered":"\n<p><strong>Ciudad de Panam\u00e1, junio 2025 \u2014 <\/strong>La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la ciudadan\u00eda.<\/p>\n\n\n\n<p>Entre los meses de abril a junio de 2025, Fundaci\u00f3n Natura realiz\u00f3 una serie de convocatorias p\u00fablicas dirigidas a empresas, organizaciones y profesionales, en el marco de los programas y proyectos que impulsa para fortalecer la sostenibilidad ambiental en el pa\u00eds. Estas convocatorias representan una parte esencial de nuestra estrategia para avanzar de forma colaborativa hacia una gesti\u00f3n ambiental efectiva.<\/p>\n\n\n\n<p>Durante este per\u00edodo, se destacaron dos convocatorias en el marco del Proyecto Conserva Aves, una de ellas orientada espec\u00edficamente al componente de equidad. Este proyecto tiene como objetivo la creaci\u00f3n y gesti\u00f3n sostenible de \u00e1reas protegidas municipales para salvaguardar especies de aves amenazadas, tanto end\u00e9micas como migratorias, y los h\u00e1bitats en los que dependen para su supervivencia.<\/p>\n\n\n\n<p>Tambi\u00e9n se llevaron a cabo convocatorias vinculadas al Fondo FIDECO (Fideicomiso Ecol\u00f3gico de Panam\u00e1), dirigidas a iniciativas que promueven la conservaci\u00f3n de la biodiversidad en cuencas hidrogr\u00e1ficas como las del Canal de Panam\u00e1, Chiriqu\u00ed Viejo y Santa Mar\u00eda y las subcuencas del r\u00edo Boquer\u00f3n, Cais\u00e1n, Trinidad y microcuenca del r\u00edo Gallito, as\u00ed como en \u00e1reas protegidas prioritarias como el Parque Nacional Chagres y el Parque Nacional Dari\u00e9n. Adicionalmente, se abri\u00f3 una convocatoria bajo la modalidad de Proyecto Solicitado, destinada a propuestas ambientales presentadas por organizaciones no gubernamentales (ONG), organizaciones de base comunitaria (OBC) y otras entidades afines.<\/p>\n\n\n\n<p>En alianza con el Ministerio de Ambiente (MiAMBIENTE), el Canal de Panam\u00e1, el Programa de las Naciones Unidas para el Medio Ambiente (PNUMA), la Oficina de las Naciones Unidas de Servicios para Proyectos (UNOPS) y Banistmo, se publicaron convocatorias adicionales para la contrataci\u00f3n de apoyo t\u00e9cnico especializado. Estas incluyeron consultor\u00edas relacionadas al dise\u00f1o y Reproducci\u00f3n de Materiales Did\u00e1cticos para el Fomento de la Cultura y Cuidado Ambiental de la Cuenca del r\u00edo Indio, con cosecha de agua, integraci\u00f3n de g\u00e9nero e inclusi\u00f3n social, as\u00ed como vacantes para perfiles clave como coordinador de proyectos, programador de monitoreo y evaluaci\u00f3n y especialista en dise\u00f1o web, en el marco de la Iniciativa para la Transparencia en la Acci\u00f3n Clim\u00e1tica (ICAT). <\/p>\n\n\n\n<p>En total, Fundaci\u00f3n Natura lanz\u00f3 6 convocatorias de proyectos, 1 consultor\u00eda especializada y 8 vacantes t\u00e9cnicas y profesionales durante el trimestre. Pr\u00f3ximamente se estar\u00e1n compartiendo los resultados y adjudicaciones correspondientes en la p\u00e1gina web de la Fundaci\u00f3n. Estos procesos reflejan nuestro compromiso con una gesti\u00f3n participativa, eficiente e innovadora, orientada a impulsar soluciones sostenibles que respondan a los desaf\u00edos ambientales actuales del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de Panam\u00e1, junio 2025 \u2014 La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-12669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos<\/title>\n<meta name=\"description\" content=\"Ciudad de Panam\u00e1, junio 2025 \u2014 La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Ciudad%20de%20Panam\u00e1,%20junio%202025%20\u2014%20La%20transparencia%20es%20uno%20de%20los%20pilares%20fundamentales%20de%20Fundaci\u00f3n%20Natura.%20Como%20organizaci\u00f3n%20comprometida%20con%20la%20conservaci\u00f3n%20y%20protecci\u00f3n%20de%20la%20naturaleza,%20y%20el%20desarrollo%20sostenible%20de%20Panam\u00e1,%20promovemos%20procesos%20abiertos%20y%20responsables%20que%20garanticen%20el%20adecuado%20uso%20de%20los%20recursos,%20generando%20confianza%20en%20nuestros%20donantes,%20aliados%20y%20la&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos\" \/>\n<meta property=\"og:description\" content=\"Ciudad de Panam\u00e1, junio 2025 \u2014 La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci&oacute;n Natura\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naturapma\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-30T21:15:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T21:21:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/07\/Piji-2-de-221.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Comunicaciones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@naturapanama\" \/>\n<meta name=\"twitter:site\" content=\"@naturapanama\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/\"},\"author\":{\"name\":\"Comunicaciones\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#\\\/schema\\\/person\\\/9a635c59f5d7459c52e2d5ce79952b48\"},\"headline\":\"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos\",\"datePublished\":\"2025-06-30T21:15:20+00:00\",\"dateModified\":\"2025-07-28T21:21:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Piji-2-de-221.webp\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/\",\"name\":\"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos &#060; Fundaci&oacute;n Natura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Piji-2-de-221.webp\",\"datePublished\":\"2025-06-30T21:15:20+00:00\",\"dateModified\":\"2025-07-28T21:21:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Piji-2-de-221.webp\",\"contentUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Piji-2-de-221.webp\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/naturapanama.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/\",\"name\":\"Fundaci\u00f3n Natura\",\"description\":\"Fundaci&oacute;n Natura es reconocida como gestor de recursos, que lidera e innova en la conservaci&oacute;n y el manejo sostenible de ecosistemas y su biodiversidad en las cuencas hidrogr&aacute;ficas y &aacute;reas marino costeras priorizadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#organization\",\"name\":\"Fundacion Natura\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-Recurso-3@4x.png\",\"contentUrl\":\"https:\\\/\\\/naturapanama.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-Recurso-3@4x.png\",\"width\":512,\"height\":512,\"caption\":\"Fundacion Natura\"},\"image\":{\"@id\":\"https:\\\/\\\/naturapanama.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/naturapma\\\/\",\"https:\\\/\\\/x.com\\\/naturapanama\",\"https:\\\/\\\/www.instagram.com\\\/naturapma\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWu_h9ovqfg_vR2RlGe9UfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/naturapanama.org\\\/#\\\/schema\\\/person\\\/9a635c59f5d7459c52e2d5ce79952b48\",\"name\":\"Comunicaciones\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos","description":"Ciudad de Panam\u00e1, junio 2025 \u2014 La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Ciudad de Panam\u00e1, junio 2025 \u2014 La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la&hellip;","og_locale":"en_US","og_type":"article","og_title":"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos","og_description":"Ciudad de Panam\u00e1, junio 2025 \u2014 La transparencia es uno de los pilares fundamentales de Fundaci\u00f3n Natura. Como organizaci\u00f3n comprometida con la conservaci\u00f3n y protecci\u00f3n de la naturaleza, y el desarrollo sostenible de Panam\u00e1, promovemos procesos abiertos y responsables que garanticen el adecuado uso de los recursos, generando confianza en nuestros donantes, aliados y la&hellip;","og_url":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/","og_site_name":"Fundaci&oacute;n Natura","article_publisher":"https:\/\/www.facebook.com\/naturapma\/","article_published_time":"2025-06-30T21:15:20+00:00","article_modified_time":"2025-07-28T21:21:50+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/07\/Piji-2-de-221.webp","type":"image\/webp"}],"author":"Comunicaciones","twitter_card":"summary_large_image","twitter_creator":"@naturapanama","twitter_site":"@naturapanama","twitter_misc":{"Written by":"Comunicaciones","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#article","isPartOf":{"@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/"},"author":{"name":"Comunicaciones","@id":"https:\/\/naturapanama.org\/#\/schema\/person\/9a635c59f5d7459c52e2d5ce79952b48"},"headline":"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos","datePublished":"2025-06-30T21:15:20+00:00","dateModified":"2025-07-28T21:21:50+00:00","mainEntityOfPage":{"@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/"},"wordCount":518,"publisher":{"@id":"https:\/\/naturapanama.org\/#organization"},"image":{"@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#primaryimage"},"thumbnailUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/07\/Piji-2-de-221.webp","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/","url":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/","name":"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos &#060; Fundaci&oacute;n Natura","isPartOf":{"@id":"https:\/\/naturapanama.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#primaryimage"},"image":{"@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#primaryimage"},"thumbnailUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/07\/Piji-2-de-221.webp","datePublished":"2025-06-30T21:15:20+00:00","dateModified":"2025-07-28T21:21:50+00:00","breadcrumb":{"@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#primaryimage","url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/07\/Piji-2-de-221.webp","contentUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2025\/07\/Piji-2-de-221.webp","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/naturapanama.org\/en\/fundacion-natura-reafirma-su-compromiso-con-la-transparencia-y-la-conservacion-ambiental-a-traves-de-procesos-de-contratacion-abiertos-y-participativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/naturapanama.org\/"},{"@type":"ListItem","position":2,"name":"Fundaci\u00f3n Natura reafirma su compromiso con la transparencia y la conservaci\u00f3n ambiental a trav\u00e9s de procesos de contrataci\u00f3n abiertos y participativos"}]},{"@type":"WebSite","@id":"https:\/\/naturapanama.org\/en\/#website","url":"https:\/\/naturapanama.org\/en\/","name":"Fundaci\u00f3n Natura","description":"Fundaci&oacute;n Natura es reconocida como gestor de recursos, que lidera e innova en la conservaci&oacute;n y el manejo sostenible de ecosistemas y su biodiversidad en las cuencas hidrogr&aacute;ficas y &aacute;reas marino costeras priorizadas","publisher":{"@id":"https:\/\/naturapanama.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturapanama.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/naturapanama.org\/en\/#organization","name":"Fundacion Natura","url":"https:\/\/naturapanama.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturapanama.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/naturapanama.org\/wp-content\/uploads\/2021\/08\/cropped-Recurso-3@4x.png","contentUrl":"https:\/\/naturapanama.org\/wp-content\/uploads\/2021\/08\/cropped-Recurso-3@4x.png","width":512,"height":512,"caption":"Fundacion Natura"},"image":{"@id":"https:\/\/naturapanama.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naturapma\/","https:\/\/x.com\/naturapanama","https:\/\/www.instagram.com\/naturapma\/","https:\/\/www.youtube.com\/channel\/UCWu_h9ovqfg_vR2RlGe9UfA"]},{"@type":"Person","@id":"https:\/\/naturapanama.org\/#\/schema\/person\/9a635c59f5d7459c52e2d5ce79952b48","name":"Comunicaciones"}]}},"_links":{"self":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/12669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/comments?post=12669"}],"version-history":[{"count":1,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/12669\/revisions"}],"predecessor-version":[{"id":12671,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/posts\/12669\/revisions\/12671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/media\/12672"}],"wp:attachment":[{"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/media?parent=12669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/categories?post=12669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturapanama.org\/en\/wp-json\/wp\/v2\/tags?post=12669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}